{"id":982,"date":"2023-03-18T21:56:15","date_gmt":"2023-03-18T20:56:15","guid":{"rendered":"https:\/\/skc-nidderau.de\/?p=982"},"modified":"2023-03-18T21:56:16","modified_gmt":"2023-03-18T20:56:16","slug":"woelfersheimer-kegler-werden-zum-stolperstein","status":"publish","type":"post","link":"https:\/\/skc-nidderau.de\/index.php\/2023\/03\/18\/woelfersheimer-kegler-werden-zum-stolperstein\/","title":{"rendered":"W\u00f6lfersheimer Kegler werden zum Stolperstein"},"content":{"rendered":"<p><strong>Nidderauer Sportkegler unterliegen klar <\/strong><\/p>\n<p>Die Gegner, die nach Nidderau anreisten, kamen von der SG W\u00f6lfersheim\/Wohnbach 2.<\/p>\n<p>Der Tabellennachbar war der erwartet schwere Gegner und lieferte ab. Die W\u00f6lfersheimer gewannen letztendlich verdient das Spiel.<\/p>\n<p>3:5 Mannschaftspunkte (MP) und 2982:3116 Holz sprechen eine klare Sprache. Hervorzuheben ist Helge L\u00fcftner. Der Gast erzielte auf den Bahnen der KuS-Halle 567 Holz, 4 Spielpunkte (SP) und den Mannschaftspunkt.<\/p>\n<p>Von den Nidderauern \u00fcberzeugte nur Hans Weber (535, 3 SP, 1 MP) und Jens Kittel (515, 3 SP, 1 MP).<\/p>\n<p>Den dritten Mannschaftspunkt holte Tim Schulze (492,2,5 SP).<\/p>\n<p>Die weiteren Spieler waren Bernd Unthan (486,1, 0), Max Unthan (491,1, 0) und Sven Fischer (463, 0, 0).<\/p>\n<p>Im letzten Saisonspiel geht die Reise nach M\u00fchlheim am Main.<\/p>\n<p>Nidderau 2 hatte spielfrei und das letzte Saisonspiel findet in Florstadt statt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nidderauer Sportkegler unterliegen klar Die Gegner, die nach Nidderau anreisten, kamen von der SG W\u00f6lfersheim\/Wohnbach 2. Der Tabellennachbar war der erwartet schwere Gegner und lieferte ab. Die W\u00f6lfersheimer gewannen letztendlich verdient das Spiel. 3:5 Mannschaftspunkte (MP) und 2982:3116 Holz sprechen eine klare Sprache. Hervorzuheben ist Helge L\u00fcftner. Der Gast erzielte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/posts\/982"}],"collection":[{"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/comments?post=982"}],"version-history":[{"count":1,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/posts\/982\/revisions"}],"predecessor-version":[{"id":983,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/posts\/982\/revisions\/983"}],"wp:attachment":[{"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/media?parent=982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/categories?post=982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skc-nidderau.de\/index.php\/wp-json\/wp\/v2\/tags?post=982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}